{"id":2369,"count":1,"description":"","link":"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment","name":"work capability assessment","slug":"work-capability-assessment","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>work capability assessment Archives - alt.cardiff<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"work capability assessment Archives - alt.cardiff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment\" \/>\n<meta property=\"og:site_name\" content=\"alt.cardiff\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jomec.co.uk\/altcardiff\/#website\",\"url\":\"https:\/\/www.jomec.co.uk\/altcardiff\/\",\"name\":\"alt.cardiff\",\"description\":\"If it\\u2019s offbeat and in Cardiff then it\\u2019s online here.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.jomec.co.uk\/altcardiff\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment#webpage\",\"url\":\"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment\",\"name\":\"work capability assessment Archives - alt.cardiff\",\"isPartOf\":{\"@id\":\"https:\/\/www.jomec.co.uk\/altcardiff\/#website\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jomec.co.uk\/altcardiff\/tag\/work-capability-assessment\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.jomec.co.uk\/altcardiff\/wp-json\/wp\/v2\/tags\/2369"}],"collection":[{"href":"https:\/\/www.jomec.co.uk\/altcardiff\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.jomec.co.uk\/altcardiff\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.jomec.co.uk\/altcardiff\/wp-json\/wp\/v2\/posts?tags=2369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}